{"id":321,"date":"2025-05-28T13:29:34","date_gmt":"2025-05-28T13:29:34","guid":{"rendered":"https:\/\/planbet.cafe\/bj1\/?page_id=321"},"modified":"2025-06-14T06:34:04","modified_gmt":"2025-06-14T06:34:04","slug":"100-first-deposit","status":"publish","type":"page","link":"https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/","title":{"rendered":"100% sur le premier d\u00e9p\u00f4t"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":237,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-321","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>100% sur votre premier d\u00e9p\u00f4t chez PlanBet B\u00e9nin \u1409 65000 XOF!<\/title>\n<meta name=\"description\" content=\"Doublez votre premier d\u00e9p\u00f4t - recevez jusqu&#039;\u00e0 65 000 XOF sur votre compte. Une inscription rapide, une proc\u00e9dure simple et d&#039;incroyables opportunit\u00e9s de gagner! Ne ratez pas votre chance - le bonus n&#039;est disponible qu&#039;une seule fois!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"100% sur votre premier d\u00e9p\u00f4t chez PlanBet B\u00e9nin \u1409 65000 XOF!\" \/>\n<meta property=\"og:description\" content=\"Doublez votre premier d\u00e9p\u00f4t - recevez jusqu&#039;\u00e0 65 000 XOF sur votre compte. Une inscription rapide, une proc\u00e9dure simple et d&#039;incroyables opportunit\u00e9s de gagner! Ne ratez pas votre chance - le bonus n&#039;est disponible qu&#039;une seule fois!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/\" \/>\n<meta property=\"og:site_name\" content=\"PB BJ1\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-14T06:34:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/bonus\\\/100-first-deposit\\\/\",\"url\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/bonus\\\/100-first-deposit\\\/\",\"name\":\"100% sur votre premier d\u00e9p\u00f4t chez PlanBet B\u00e9nin \u1409 65000 XOF!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/#website\"},\"datePublished\":\"2025-05-28T13:29:34+00:00\",\"dateModified\":\"2025-06-14T06:34:04+00:00\",\"description\":\"Doublez votre premier d\u00e9p\u00f4t - recevez jusqu'\u00e0 65 000 XOF sur votre compte. Une inscription rapide, une proc\u00e9dure simple et d'incroyables opportunit\u00e9s de gagner! Ne ratez pas votre chance - le bonus n'est disponible qu'une seule fois!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/bonus\\\/100-first-deposit\\\/#breadcrumb\"},\"inLanguage\":\"fr-BJ\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/bonus\\\/100-first-deposit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/bonus\\\/100-first-deposit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bonus\",\"item\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/bonus\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"100% sur le premier d\u00e9p\u00f4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/#website\",\"url\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/\",\"name\":\"PB BJ1\",\"description\":\"My WordPress Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/planbet.cafe\\\/bj1\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BJ\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"100% sur votre premier d\u00e9p\u00f4t chez PlanBet B\u00e9nin \u1409 65000 XOF!","description":"Doublez votre premier d\u00e9p\u00f4t - recevez jusqu'\u00e0 65 000 XOF sur votre compte. Une inscription rapide, une proc\u00e9dure simple et d'incroyables opportunit\u00e9s de gagner! Ne ratez pas votre chance - le bonus n'est disponible qu'une seule fois!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"100% sur votre premier d\u00e9p\u00f4t chez PlanBet B\u00e9nin \u1409 65000 XOF!","og_description":"Doublez votre premier d\u00e9p\u00f4t - recevez jusqu'\u00e0 65 000 XOF sur votre compte. Une inscription rapide, une proc\u00e9dure simple et d'incroyables opportunit\u00e9s de gagner! Ne ratez pas votre chance - le bonus n'est disponible qu'une seule fois!","og_url":"https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/","og_site_name":"PB BJ1","article_modified_time":"2025-06-14T06:34:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/","url":"https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/","name":"100% sur votre premier d\u00e9p\u00f4t chez PlanBet B\u00e9nin \u1409 65000 XOF!","isPartOf":{"@id":"https:\/\/planbet.cafe\/bj1\/#website"},"datePublished":"2025-05-28T13:29:34+00:00","dateModified":"2025-06-14T06:34:04+00:00","description":"Doublez votre premier d\u00e9p\u00f4t - recevez jusqu'\u00e0 65 000 XOF sur votre compte. Une inscription rapide, une proc\u00e9dure simple et d'incroyables opportunit\u00e9s de gagner! Ne ratez pas votre chance - le bonus n'est disponible qu'une seule fois!","breadcrumb":{"@id":"https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/#breadcrumb"},"inLanguage":"fr-BJ","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/planbet.cafe\/bj1\/bonus\/100-first-deposit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/planbet.cafe\/bj1\/"},{"@type":"ListItem","position":2,"name":"Bonus","item":"https:\/\/planbet.cafe\/bj1\/bonus\/"},{"@type":"ListItem","position":3,"name":"100% sur le premier d\u00e9p\u00f4t"}]},{"@type":"WebSite","@id":"https:\/\/planbet.cafe\/bj1\/#website","url":"https:\/\/planbet.cafe\/bj1\/","name":"PB BJ1","description":"My WordPress Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planbet.cafe\/bj1\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BJ"}]}},"_links":{"self":[{"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/pages\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":7,"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/pages\/321\/revisions"}],"predecessor-version":[{"id":393,"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/pages\/321\/revisions\/393"}],"up":[{"embeddable":true,"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/pages\/237"}],"wp:attachment":[{"href":"https:\/\/planbet.cafe\/bj1\/wp-json\/wp\/v2\/media?parent=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}